{"id":24610,"date":"2025-09-09T09:37:24","date_gmt":"2025-09-09T02:37:24","guid":{"rendered":"https:\/\/cht.rmutsv.ac.th\/ruts\/?p=24610"},"modified":"2025-09-09T09:37:24","modified_gmt":"2025-09-09T02:37:24","slug":"graduat-67-2","status":"publish","type":"post","link":"https:\/\/cht.rmutsv.ac.th\/ruts\/2025\/09\/09\/24610\/graduat-67-2\/","title":{"rendered":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e21\u0e17\u0e23.\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567"},"content":{"rendered":"\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e23\u0e28.\u0e1b\u0e23\u0e30\u0e0a\u0e35\u0e1e \u0e0a\u0e39\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 80 \u0e1e\u0e23\u0e23\u0e29\u0e32 5 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2550 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e01\u0e48\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e1e\u0e34\u0e18\u0e35\u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e08\u0e23\u0e34\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568 \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e09\u0e25\u0e2d\u0e07\u0e2a\u0e34\u0e23\u0e34\u0e23\u0e32\u0e0a\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e04\u0e23\u0e1a 60 \u0e1b\u0e35 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e07\u0e02\u0e25\u0e32<br>\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e27\u0e31\u0e08\u0e19\u0e4c \u0e18\u0e31\u0e0d\u0e23\u0e2a \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e42\u0e0a\u0e04 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e22\u0e48\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e20\u0e32\u0e1e\u0e2b\u0e21\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e37\u0e49\u0e21\u0e1b\u0e34\u0e15\u0e34\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08<br>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e21\u0e17\u0e23.\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e15\u0e23\u0e31\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e02\u0e1a\u0e27\u0e19\u0e41\u0e16\u0e27\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1e\u0e34\u0e18\u0e35\u0e0b\u0e49\u0e2d\u0e21 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e42\u0e0a\u0e04 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e22\u0e48\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e27\u0e32\u0e17\u0e41\u0e01\u0e48\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e17\u0e38\u0e01\u0e04\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c<br>\u0e20\u0e32\u0e1e\/\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07 : \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e41\u0e01\u0e48\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e0a\u0e38\u0e21\u0e14\u0e35<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"531\" data-id=\"24613\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/536268370_1352497843542402_2225365334373156652_n_0-1024x531.jpg\" alt=\"\" class=\"wp-image-24613\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/536268370_1352497843542402_2225365334373156652_n_0-1024x531.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/536268370_1352497843542402_2225365334373156652_n_0-300x155.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/536268370_1352497843542402_2225365334373156652_n_0-768x398.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/536268370_1352497843542402_2225365334373156652_n_0-1536x796.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/536268370_1352497843542402_2225365334373156652_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">default<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"24643\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542760245_1352513743540812_6283368112642630472_n_0-683x1024.jpg\" alt=\"\" class=\"wp-image-24643\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542760245_1352513743540812_6283368112642630472_n_0-683x1024.jpg 683w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542760245_1352513743540812_6283368112642630472_n_0-200x300.jpg 200w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542760245_1352513743540812_6283368112642630472_n_0-768x1152.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542760245_1352513743540812_6283368112642630472_n_0-1024x1536.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542760245_1352513743540812_6283368112642630472_n_0.jpg 1365w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"24616\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758057_1352513706874149_6042215182110076445_n_0-683x1024.jpg\" alt=\"\" class=\"wp-image-24616\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758057_1352513706874149_6042215182110076445_n_0-683x1024.jpg 683w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758057_1352513706874149_6042215182110076445_n_0-200x300.jpg 200w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758057_1352513706874149_6042215182110076445_n_0-768x1152.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758057_1352513706874149_6042215182110076445_n_0-1024x1536.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758057_1352513706874149_6042215182110076445_n_0.jpg 1365w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24637\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542755898_1352513720207481_4409074355296294787_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24637\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542755898_1352513720207481_4409074355296294787_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542755898_1352513720207481_4409074355296294787_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542755898_1352513720207481_4409074355296294787_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542755898_1352513720207481_4409074355296294787_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542755898_1352513720207481_4409074355296294787_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24622\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756445_1352516096873910_2870156778915717678_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24622\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756445_1352516096873910_2870156778915717678_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756445_1352516096873910_2870156778915717678_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756445_1352516096873910_2870156778915717678_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756445_1352516096873910_2870156778915717678_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756445_1352516096873910_2870156778915717678_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"24646\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756825_1352513893540797_1433037839664627707_n_0-1024x576.jpg\" alt=\"\" class=\"wp-image-24646\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756825_1352513893540797_1433037839664627707_n_0-1024x576.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756825_1352513893540797_1433037839664627707_n_0-300x169.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756825_1352513893540797_1433037839664627707_n_0-768x432.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756825_1352513893540797_1433037839664627707_n_0-1536x864.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542756825_1352513893540797_1433037839664627707_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">default<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24640\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758138_1352517090207144_693579726724103226_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24640\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758138_1352517090207144_693579726724103226_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758138_1352517090207144_693579726724103226_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758138_1352517090207144_693579726724103226_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758138_1352517090207144_693579726724103226_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758138_1352517090207144_693579726724103226_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24628\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758597_1352497923542394_4479580965104251535_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24628\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758597_1352497923542394_4479580965104251535_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758597_1352497923542394_4479580965104251535_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758597_1352497923542394_4479580965104251535_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758597_1352497923542394_4479580965104251535_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/542758597_1352497923542394_4479580965104251535_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24619\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/543576334_1352497890209064_1243579851025851223_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24619\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/543576334_1352497890209064_1243579851025851223_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/543576334_1352497890209064_1243579851025851223_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/543576334_1352497890209064_1243579851025851223_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/543576334_1352497890209064_1243579851025851223_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/543576334_1352497890209064_1243579851025851223_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24634\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545354258_1355706516554868_7729835650599407776_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24634\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545354258_1355706516554868_7729835650599407776_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545354258_1355706516554868_7729835650599407776_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545354258_1355706516554868_7729835650599407776_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545354258_1355706516554868_7729835650599407776_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545354258_1355706516554868_7729835650599407776_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24625\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545613383_1355706149888238_5055913468007825392_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-24625\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545613383_1355706149888238_5055913468007825392_n_0-1024x683.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545613383_1355706149888238_5055913468007825392_n_0-300x200.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545613383_1355706149888238_5055913468007825392_n_0-768x512.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545613383_1355706149888238_5055913468007825392_n_0-1536x1024.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545613383_1355706149888238_5055913468007825392_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" data-id=\"24631\" src=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545626777_1355706113221575_5259981330823327248_n_0-1024x544.jpg\" alt=\"\" class=\"wp-image-24631\" srcset=\"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545626777_1355706113221575_5259981330823327248_n_0-1024x544.jpg 1024w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545626777_1355706113221575_5259981330823327248_n_0-300x159.jpg 300w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545626777_1355706113221575_5259981330823327248_n_0-768x408.jpg 768w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545626777_1355706113221575_5259981330823327248_n_0-1536x816.jpg 1536w, https:\/\/cht.rmutsv.ac.th\/ruts\/wp-content\/uploads\/2025\/09\/545626777_1355706113221575_5259981330823327248_n_0.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e28 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-24610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-public-relations"],"acf":[],"_links":{"self":[{"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/posts\/24610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/comments?post=24610"}],"version-history":[{"count":1,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/posts\/24610\/revisions"}],"predecessor-version":[{"id":24652,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/posts\/24610\/revisions\/24652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/media\/24649"}],"wp:attachment":[{"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/media?parent=24610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/categories?post=24610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cht.rmutsv.ac.th\/ruts\/wp-json\/wp\/v2\/tags?post=24610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}